{"id":17524,"date":"2024-09-02T17:00:00","date_gmt":"2024-09-02T20:00:00","guid":{"rendered":"https:\/\/staging.vetanco.com\/br\/?p=17524"},"modified":"2024-09-17T20:59:36","modified_gmt":"2024-09-17T23:59:36","slug":"controle-do-cascudinho-tema-workshop-cobb-vantress","status":"publish","type":"post","link":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/","title":{"rendered":"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress"},"content":{"rendered":"<p>O controle do cascudinho (<em>Alphitobius diaperinus<\/em>) est\u00e1 entre as medidas e procedimentos de cuidados de um programa efetivo de biosseguridade av\u00edcola. Isso se deve ao fato de que esse inseto \u00e9 uma das principais pragas da avicultura mundial. Consequentemente, ele \u00e9 respons\u00e1vel pela transmiss\u00e3o de uma ampla variedade de pat\u00f3genos.<\/p>\n<p>A <a href=\"https:\/\/www.cobbgenetics.com\/\" target=\"_blank\" rel=\"noopener\">Cobb-Vantress<\/a> \u00e9 um dos nossos principais clientes no estado de S\u00e3o Paulo e a maior empresa de gen\u00e9tica de avicultura no mundo. Recentemente, a empresa promoveu seu primeiro workshop de controle de pragas.<\/p>\n<p>A Vetanco participou da iniciativa atrav\u00e9s de uma palestra sobre biosseguridade e manejo integrado de cascudinhos.\u00a0<\/p>\n<h1>Autoridade no assunto<\/h1>\n<p>H\u00e1 mais de 20 anos, a Vetanco faz a diferen\u00e7a no controle do cascudinho, unindo experi\u00eancia, tecnologia e conhecimento. Dessa forma, a empresa demonstra sua autoridade no assunto.<\/p>\n<p>Al\u00e9m disso, a companhia oferece aos clientes a Plataforma Vetancid, que \u00e9 a mais completa do mercado. Essa plataforma ajuda a fortalecer a biosseguridade na propriedade, garantindo um produto final de qualidade. Al\u00e9m disso, preconiza a seguran\u00e7a alimentar, bem-estar animal e sustentabilidade. Assim, a Vetanco reafirma seu slogan de autoridade quando o assunto \u00e9 o controle do cascudinho. \u00a0<\/p>\n<p>No workshop, o tema foi abordado pelo nosso assistente t\u00e9cnico Aves Roney Santos, respons\u00e1vel pela regi\u00e3o. Al\u00e9m dele, acompanhou a programa\u00e7\u00e3o Felipe Chiarelli, Coordenador de Territ\u00f3rio Aves.<\/p>\n<p>Agradecemos especialmente\u00a0\u00e0 Analista de Bem-estar Animal e Controle de Pragas na Cobb-Vantress, Gracieli Araujo Castilho, respons\u00e1vel pela concretiza\u00e7\u00e3o desta importante iniciativa.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":17528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,57],"tags":[528,51],"class_list":["post-17524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-palestras-tecnicas","tag-medidas-de-biosseguridade","tag-vetanco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress - Vetanco Brasil<\/title>\n<meta name=\"description\" content=\"A Vetanco ministrou uma palestra voltada ao controle do cascudinho no primeiro workshop de controle de pragas da Cobb-Vantress.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress - Vetanco Brasil\" \/>\n<meta property=\"og:description\" content=\"A Vetanco ministrou uma palestra voltada ao controle do cascudinho no primeiro workshop de controle de pragas da Cobb-Vantress.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-02T20:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T23:59:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.vetanco.com\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/\",\"name\":\"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress - Vetanco Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg\",\"datePublished\":\"2024-09-02T20:00:00+00:00\",\"dateModified\":\"2024-09-17T23:59:36+00:00\",\"author\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\"},\"description\":\"A Vetanco ministrou uma palestra voltada ao controle do cascudinho no primeiro workshop de controle de pragas da Cobb-Vantress.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#primaryimage\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/staging.vetanco.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\",\"url\":\"https:\/\/staging.vetanco.com\/br\/\",\"name\":\"Vetanco Brasil\",\"description\":\"Produtos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\",\"name\":\"Simone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"caption\":\"Simone\"},\"url\":\"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress - Vetanco Brasil","description":"A Vetanco ministrou uma palestra voltada ao controle do cascudinho no primeiro workshop de controle de pragas da Cobb-Vantress.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/","og_locale":"pt_BR","og_type":"article","og_title":"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress - Vetanco Brasil","og_description":"A Vetanco ministrou uma palestra voltada ao controle do cascudinho no primeiro workshop de controle de pragas da Cobb-Vantress.\u00a0","og_url":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/","og_site_name":"Vetanco Brasil","article_published_time":"2024-09-02T20:00:00+00:00","article_modified_time":"2024-09-17T23:59:36+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/staging.vetanco.com\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg","type":"image\/jpeg"}],"author":"Simone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Simone","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/","url":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/","name":"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress - Vetanco Brasil","isPartOf":{"@id":"https:\/\/staging.vetanco.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#primaryimage"},"image":{"@id":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg","datePublished":"2024-09-02T20:00:00+00:00","dateModified":"2024-09-17T23:59:36+00:00","author":{"@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de"},"description":"A Vetanco ministrou uma palestra voltada ao controle do cascudinho no primeiro workshop de controle de pragas da Cobb-Vantress.\u00a0","breadcrumb":{"@id":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#primaryimage","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/controle-cascudinho-medidas-biosseguridade-vetanco.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/staging.vetanco.com\/br\/controle-do-cascudinho-tema-workshop-cobb-vantress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/staging.vetanco.com\/br\/"},{"@type":"ListItem","position":2,"name":"Controle do cascudinho \u00e9 tema de workshop na Cobb-Vantress"}]},{"@type":"WebSite","@id":"https:\/\/staging.vetanco.com\/br\/#website","url":"https:\/\/staging.vetanco.com\/br\/","name":"Vetanco Brasil","description":"Produtos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de","name":"Simone","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","caption":"Simone"},"url":"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/17524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/comments?post=17524"}],"version-history":[{"count":5,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/17524\/revisions"}],"predecessor-version":[{"id":17530,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/17524\/revisions\/17530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media\/17528"}],"wp:attachment":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media?parent=17524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/categories?post=17524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/tags?post=17524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}