{"id":18274,"date":"2024-03-13T10:58:00","date_gmt":"2024-03-13T13:58:00","guid":{"rendered":"https:\/\/staging.vetanco.com\/br\/?p=18274"},"modified":"2024-09-27T09:45:07","modified_gmt":"2024-09-27T12:45:07","slug":"liderancas-reunidas-visam-entrega-de-valor","status":"publish","type":"post","link":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/","title":{"rendered":"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024"},"content":{"rendered":"<p>As lideran\u00e7as da Vetanco se reuniram visando a entrega de valor, em um evento 100% carbon free. Estamos falando da Conven\u00e7\u00e3o de Vendas 2024, que aconteceu de 4 a 8 de mar\u00e7o, em Florian\u00f3polis\/SC.<\/p>\n<p>Atrav\u00e9s da Conven\u00e7\u00e3o de Vendas, buscamos validar os planejamentos estrat\u00e9gicos junto \u00e0s equipes T\u00e9cnica e Comercial, alinhar posicionamentos, aproximar os times e renovar as energias.\u00a0<\/p>\n<p>Este ano, desenvolvemos o tema &#8220;Evoluindo juntos: paix\u00e3o pelas pessoas!&#8221;, que reflete a vis\u00e3o da Vetanco. Aspiramos ser refer\u00eancia na gera\u00e7\u00e3o de valor para o cliente e oferecer as melhores solu\u00e7\u00f5es. Al\u00e9m de manter nossa paix\u00e3o pelas pessoas e pelo agroneg\u00f3cio.<\/p>\n<p>\u201cEntendemos que todas as nossas entregas s\u00e3o pautadas no respeito e consideramos as pessoas que ser\u00e3o impactadas nos processos. Isso faz parte\u00a0de nossos valores organizacionais, da nossa miss\u00e3o. De uma maneira leve, todas as for\u00e7as de cada integrante do time foram evidenciadas em nossa Conven\u00e7\u00e3o\u201d, conta a Coordenadora de Gest\u00e3o de Pessoas da Vetanco, G\u00e9ssica Let\u00edcia Oltramari.<\/p>\n<h1>Entrega de valor<\/h1>\n<p>A Conven\u00e7\u00e3o, com foco na entrega de valor, integrou a equipe. Ao mesmo tempo, promoveu o reencontro de colegas e apresentou os novos profissionais que ingressaram recentemente na empresa.\u00a0<\/p>\n<p>\u201c\u00c9 justamente atrav\u00e9s de momentos como os que s\u00e3o proporcionados ao longo da nossa Conven\u00e7\u00e3o que a Vetanco alcan\u00e7ar\u00e1 seus objetivos. Primeiramente, todos devem estar satisfeitos, felizes e interagindo como time. Por segundo, precisam estar alinhados com as expectativas da companhia e com nossas metas para o ano\u201d, ressalta o Diretor T\u00e9cnico\/Comercial, Tiago Urbano.<\/p>\n<p>A programa\u00e7\u00e3o acolheu e escutou os participantes, oportunizou compartilhar conhecimentos, o engajamento e a proximidade. Desde momentos descontra\u00eddos at\u00e9 um painel t\u00e9cnico, os colaboradores tamb\u00e9m tiveram a oportunidade de aprender mais sobre comunica\u00e7\u00e3o estrat\u00e9gica e a conhecer melhor seus colegas, com quem compartilham os desafios e conquistas.<\/p>\n<p>\u201cEnfim, um momento incr\u00edvel, o pitch, um espa\u00e7o em que o colaborador pode apresentar suas for\u00e7as e conquistas da maneira que quisesse. Alem disso, fez com que perceb\u00eassemos ainda mais as fortalezas de cada um\u201d, revela a Coordenadora de Gest\u00e3o.<\/p>\n<h1>Bluebook<\/h1>\n<p>Prova dessa paix\u00e3o pelas pessoas, cada colaborador ganhou uma edi\u00e7\u00e3o impressa do Bluebook com o slogan \u201cNosso mundo \u00e9 azul\u201d.\u00a0<\/p>\n<p>O documento incorpora em sua ess\u00eancia o Jeito Vetanco de Ser. Ou seja, a publica\u00e7\u00e3o dever\u00e1 servir como uma refer\u00eancia \u00fatil sobre princ\u00edpios de comportamento e atitudes para orientar os colaboradores em quest\u00f5es intang\u00edveis \u00e0 logomarca. Em outras palavras, o Bluebook engloba aspectos do dia a dia, de maneira natural, que condizem com o prop\u00f3sito da companhia.<\/p>\n<h1>100% Carbon Free<\/h1>\n<p>A Conven\u00e7\u00e3o de Vendas 2024 tamb\u00e9m foi o primeiro evento carbon free da empresa. Isto significa que 100% das emiss\u00f5es de carbono geradas na conven\u00e7\u00e3o ser\u00e3o neutralizadas atrav\u00e9s do projeto Envira Amaz\u00f4nia, em parceria com a Carbon Free Brasil. A iniciativa \u00e9 uma das a\u00e7\u00f5es do Programa ESG Vetanco para o decorrer do ano.<\/p>\n<p>\u201cA Vetanco tem como prop\u00f3sito, para 2024, ampliar suas a\u00e7\u00f5es de ESG. A Conven\u00e7\u00e3o envolve a quest\u00e3o da governan\u00e7a e do social e n\u00f3s quer\u00edamos complementar o evento trabalhando algumas a\u00e7\u00f5es ambientais\u201d, conta a Diretora Administrativa, Daiane Cristina de Moura M\u00fcssnich.<\/p>\n<p>Para concretizar a iniciativa, elaboramos um invent\u00e1rio de toda emiss\u00e3o de carbono no meio ambiente. Por exemplo, consideramos o deslocamento dos colaboradores, o lixo gerado durante a Conven\u00e7\u00e3o e a energia el\u00e9trica utilizada, entre outros aspectos. A partir desse documento, a Vetanco ir\u00e1 compensar a emiss\u00e3o de gases atrav\u00e9s da destina\u00e7\u00e3o dos cr\u00e9ditos de carbono ao projeto contemplado.<\/p>\n<p>\u201cPara n\u00f3s foi muito especial, pois, de uma maneira direta e pr\u00e1tica, estamos cuidando do meio ambiente, investindo nesse bem precioso que \u00e9 a biodiversidade. Assim como temos a quest\u00e3o da preserva\u00e7\u00e3o ribeirinha, beneficiada pelo projeto\u201d, ressalta Daiane.<\/p>\n<p>O projeto Envira Amaz\u00f4nia foi criado para conservar a floresta e gerar cr\u00e9ditos de carbono. Isto, atrav\u00e9s do projeto de Redu\u00e7\u00e3o de Emiss\u00f5es por Desmatamento e Degrada\u00e7\u00e3o (REDD+), que protege uma vasta \u00e1rea de floresta amaz\u00f4nica.<\/p>\n<p>A Diretora destacou a import\u00e2ncia de sensibilizar todos os colaboradores da corpora\u00e7\u00e3o sobre o prop\u00f3sito do Programa, orientando-os nas quest\u00f5es do dia a dia, al\u00e9m de mostrar como cada um pode contribuir da sua maneira.<\/p>\n<p>Cada colaborador ganhou uma camiseta alusiva ao ESG em uma trilha orientada como forma de conscientiza\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":18286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,1,45],"tags":[505,547,51],"class_list":["post-18274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esg","category-eventos","category-noticias","tag-carbon-free","tag-entrega-de-valor","tag-vetanco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024 - Vetanco Brasil<\/title>\n<meta name=\"description\" content=\"A entrega de valor pautou nossa Conven\u00e7\u00e3o de Vendas 2024 - Evoluindo juntos: paix\u00e3o pelas pessoas! -, em um evento 100% carbon free.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024 - Vetanco Brasil\" \/>\n<meta property=\"og:description\" content=\"A entrega de valor pautou nossa Conven\u00e7\u00e3o de Vendas 2024 - Evoluindo juntos: paix\u00e3o pelas pessoas! -, em um evento 100% carbon free.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-13T13:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T12:45:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.vetanco.com\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/\",\"name\":\"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024 - Vetanco Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg\",\"datePublished\":\"2024-03-13T13:58:00+00:00\",\"dateModified\":\"2024-09-27T12:45:07+00:00\",\"author\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\"},\"description\":\"A entrega de valor pautou nossa Conven\u00e7\u00e3o de Vendas 2024 - Evoluindo juntos: paix\u00e3o pelas pessoas! -, em um evento 100% carbon free.\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#primaryimage\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/staging.vetanco.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\",\"url\":\"https:\/\/staging.vetanco.com\/br\/\",\"name\":\"Vetanco Brasil\",\"description\":\"Produtos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\",\"name\":\"Simone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"caption\":\"Simone\"},\"url\":\"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024 - Vetanco Brasil","description":"A entrega de valor pautou nossa Conven\u00e7\u00e3o de Vendas 2024 - Evoluindo juntos: paix\u00e3o pelas pessoas! -, em um evento 100% carbon free.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/","og_locale":"pt_BR","og_type":"article","og_title":"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024 - Vetanco Brasil","og_description":"A entrega de valor pautou nossa Conven\u00e7\u00e3o de Vendas 2024 - Evoluindo juntos: paix\u00e3o pelas pessoas! -, em um evento 100% carbon free.","og_url":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/","og_site_name":"Vetanco Brasil","article_published_time":"2024-03-13T13:58:00+00:00","article_modified_time":"2024-09-27T12:45:07+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/staging.vetanco.com\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg","type":"image\/jpeg"}],"author":"Simone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Simone","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/","url":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/","name":"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024 - Vetanco Brasil","isPartOf":{"@id":"https:\/\/staging.vetanco.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#primaryimage"},"image":{"@id":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg","datePublished":"2024-03-13T13:58:00+00:00","dateModified":"2024-09-27T12:45:07+00:00","author":{"@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de"},"description":"A entrega de valor pautou nossa Conven\u00e7\u00e3o de Vendas 2024 - Evoluindo juntos: paix\u00e3o pelas pessoas! -, em um evento 100% carbon free.","breadcrumb":{"@id":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#primaryimage","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/entrega-de-valor-convencao-vendas-vetanco-carbon-free.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/staging.vetanco.com\/br\/liderancas-reunidas-visam-entrega-de-valor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/staging.vetanco.com\/br\/"},{"@type":"ListItem","position":2,"name":"Entrega de valor pauta Conven\u00e7\u00e3o de Vendas 2024"}]},{"@type":"WebSite","@id":"https:\/\/staging.vetanco.com\/br\/#website","url":"https:\/\/staging.vetanco.com\/br\/","name":"Vetanco Brasil","description":"Produtos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de","name":"Simone","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","caption":"Simone"},"url":"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/18274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/comments?post=18274"}],"version-history":[{"count":26,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/18274\/revisions"}],"predecessor-version":[{"id":18334,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/18274\/revisions\/18334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media\/18286"}],"wp:attachment":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media?parent=18274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/categories?post=18274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/tags?post=18274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}