{"id":22542,"date":"2015-03-26T11:48:00","date_gmt":"2015-03-26T14:48:00","guid":{"rendered":"https:\/\/staging.vetanco.com\/br\/?p=22542"},"modified":"2024-11-28T11:50:41","modified_gmt":"2024-11-28T14:50:41","slug":"vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa","status":"publish","type":"post","link":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/","title":{"rendered":"Vetanco viabiliza vinda de palestrante internacional ao SBSA"},"content":{"rendered":"<p><em>Evento que a cada ano se renova, traz em 2015 uma programa\u00e7\u00e3o de alto n\u00edvel t\u00e9cnico com palestrantes que dissertar\u00e3o sobre assuntos de aplicabilidade pr\u00e1tica para a produ\u00e7\u00e3o av\u00edcola.<\/em><\/p>\n<p>O Simp\u00f3sio Brasil Sul de Avicultura acontecer\u00e1 entre os dias 7 e 9 de abril em Chapec\u00f3\/SC, evento que chega a sua 16\u00aa edi\u00e7\u00e3o, oferecendo aos participantes palestras de alto n\u00edvel t\u00e9cnico. A Vetanco sempre presente como patrocinadora, neste ano, viabilizou a vinda do palestrante Dr. James Barton, que no dia 9 de Abril ministrar\u00e1 a palestra intitulada: Procedimentos atuais e futuros para o controle de salmoneloses nas granjas av\u00edcolas americanas: melhores pr\u00e1ticas x mundo real.<\/p>\n<h1>O palestrante<\/h1>\n<p>Dr. James Barton \u00e9 M\u00e9dico Veterin\u00e1rio, graduado pela Universidade de Arkansas e P\u00f3s-graduado pela Universidade de Louisiana. Possui resid\u00eancia no laborat\u00f3rio da Universidade da Calif\u00f3rnia-Davis. Ao longo de sua carreira de mais de 25 anos desenvolveu diversos trabalhos, possuindo expertise em bem estar animal na produ\u00e7\u00e3o de aves. Atuou em grandes empresas produtoras de frango de corte e perus nos EUA e atualmente \u00e9 Diretor de Servi\u00e7os T\u00e9cnicos da Pacific Vet Group (Arkansas\/EUA). Tamb\u00e9m \u00e9 Membro da Associa\u00e7\u00e3o Americana de Avicultura e do Comit\u00ea de Bem Estar Animal, al\u00e9m de presidente do Comit\u00ea de Seguran\u00e7a Alimentar.<\/p>\n<h1>Programa Vetanco\u00a0<\/h1>\n<p>Muitas abordagens est\u00e3o sendo utilizadas para reduzir os problemas causados por Salmonellas em aves, combinando programas de biosseguridade com a utiliza\u00e7\u00e3o de ferramentas como os probi\u00f3ticos, pr\u00e9bioticos, \u00e1cidos org\u00e2nicos e produtos que modulam a a\u00e7\u00e3o do sistema imune de mucosas.<\/p>\n<p>Temos alcan\u00e7ado avan\u00e7os e sucessos com a utiliza\u00e7\u00e3o de produtos desenvolvidos em centros de pesquisa mundialmente reconhecidos, como a Universidade de Arkansas. Oferecemos produtos e servi\u00e7os de excel\u00eancia, buscando o aprimoramento constante no combate \u00e0s Salmonellas na avicultura industrial.<\/p>\n<p>A Vetanco possui solu\u00e7\u00f5es integradas, combinando produtos inovadores com assist\u00eancia t\u00e9cnica exclusiva. O desafio das agroind\u00fastrias \u00e9 nosso compromisso: foco na redu\u00e7\u00e3o de Salmonellas, melhorando a produtividade, os riscos sanit\u00e1rios e auxiliando as empresas av\u00edcolas na manuten\u00e7\u00e3o de seus mercados exportadores. Oferecemos uma ampla variedade de produtos para o estabelecimento de um programa integral de controle de Salmonellas, tais como:<\/p>\n<p><strong>Floramax B11\u2122<\/strong> \u2013 Probi\u00f3tico espec\u00edfico de aves com efici\u00eancia comprovada contra Salmonellas;<br \/><strong>Optimizer\u2122<\/strong>&#8211; Blend de \u00e1cidos org\u00e2nicos com caracter\u00edsticas \u00fanicas de controle de enteropat\u00f3genos;<br \/><strong>Uniwall Mos\u00ae \u2013<\/strong> Aditivo pr\u00e9bi\u00f3tico com ampla presen\u00e7a no mercado brasileiro.<\/p>\n<p>Alguns questionamentos e conceitos que ser\u00e3o foco da discuss\u00e3o do Dr. Barton est\u00e3o relacionados abaixo:<\/p>\n<p><em>\u00c9 poss\u00edvel produzir aves livres de Salmonella? Sabemos onde podemos chegar com um controle ideal? A viabilidade da implanta\u00e7\u00e3o de programas de controle de Salmonella, bem como sua rela\u00e7\u00e3o custo\/efic\u00e1cia s\u00e3o bastante complexas.<\/em><\/p>\n<h1>Pr\u00e1ticas gerais<\/h1>\n<p>1) Fazer o poss\u00edvel para trabalhar com pintainhos ou peruzinhos livres de Salmonella.<\/p>\n<p>2) Monitorar a incid\u00eancia das Salmonellas.<\/p>\n<p>3) Tomar as medidas adequadas em casos de alta preval\u00eancia de Salmonellas.<\/p>\n<p>4) Estabelecer pr\u00e1ticas de biosseguridade eficazes.<\/p>\n<p>5) Maximizar o mecanismo de prote\u00e7\u00e3o pr\u00f3prio das aves: Otimiza\u00e7\u00e3o da imunidade e microbiota intestinal.<\/p>\n<p>A partir dessas informa\u00e7\u00f5es, tivemos a ideia de convidar o Dr. Barton a participar de um congresso no Brasil. Segundo ele, a modula\u00e7\u00e3o da microbiota intestinal no in\u00edcio da vida das aves \u00e9 de vital import\u00e2ncia ao processo de controle de Salmonellas. Ci\u00eancia e experi\u00eancias de campo comprovam este conceito, atualmente muito difundido.<\/p>\n<p>H\u00e1 mais de 27 anos no mercado mundial, a Vetanco \u2013 empresa atuante no Brasil com foco em aves e su\u00ednos \u2013 busca a todo instante atender o lema: \u201c<strong>SEU DESAFIO \u00c9 NOSSO COMPROMISSO<\/strong>\u201d, difundindo solu\u00e7\u00f5es t\u00e9cnicas aliadas a busca da maior produtividade e padr\u00e3o sanit\u00e1rio superior.<\/p>\n<p>O Simp\u00f3sio Brasil Sul de Avicultura \u00e9 o momento de integra\u00e7\u00e3o entre nossa equipe de colaboradores com o mercado av\u00edcola, colaborando sempre para a melhoria cont\u00ednua de processos, produtos e servi\u00e7os.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":22545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,45,57],"tags":[48,615,616,186],"class_list":["post-22542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-noticias","category-palestras-tecnicas","tag-avicultura","tag-sbsa-2","tag-simposio-brasil-sul-de-avicultura","tag-vetanco-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vetanco viabiliza vinda de palestrante internacional ao SBSA - Vetanco Brasil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vetanco viabiliza vinda de palestrante internacional ao SBSA - Vetanco Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-26T14:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T14:50:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.vetanco.com\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Simone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/\",\"name\":\"Vetanco viabiliza vinda de palestrante internacional ao SBSA - Vetanco Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png\",\"datePublished\":\"2015-03-26T14:48:00+00:00\",\"dateModified\":\"2024-11-28T14:50:41+00:00\",\"author\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\"},\"breadcrumb\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#primaryimage\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/staging.vetanco.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vetanco viabiliza vinda de palestrante internacional ao SBSA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\",\"url\":\"https:\/\/staging.vetanco.com\/br\/\",\"name\":\"Vetanco Brasil\",\"description\":\"Produtos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\",\"name\":\"Simone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"caption\":\"Simone\"},\"url\":\"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vetanco viabiliza vinda de palestrante internacional ao SBSA - Vetanco Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/","og_locale":"pt_BR","og_type":"article","og_title":"Vetanco viabiliza vinda de palestrante internacional ao SBSA - Vetanco Brasil","og_url":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/","og_site_name":"Vetanco Brasil","article_published_time":"2015-03-26T14:48:00+00:00","article_modified_time":"2024-11-28T14:50:41+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/staging.vetanco.com\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png","type":"image\/png"}],"author":"Simone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Simone","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/","url":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/","name":"Vetanco viabiliza vinda de palestrante internacional ao SBSA - Vetanco Brasil","isPartOf":{"@id":"https:\/\/staging.vetanco.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#primaryimage"},"image":{"@id":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png","datePublished":"2015-03-26T14:48:00+00:00","dateModified":"2024-11-28T14:50:41+00:00","author":{"@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de"},"breadcrumb":{"@id":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#primaryimage","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/11\/dr-barton-arkan-vetanco-floramax.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/staging.vetanco.com\/br\/vetanco-viabiliza-vinda-de-palestrante-internacional-ao-sbsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/staging.vetanco.com\/br\/"},{"@type":"ListItem","position":2,"name":"Vetanco viabiliza vinda de palestrante internacional ao SBSA"}]},{"@type":"WebSite","@id":"https:\/\/staging.vetanco.com\/br\/#website","url":"https:\/\/staging.vetanco.com\/br\/","name":"Vetanco Brasil","description":"Produtos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de","name":"Simone","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","caption":"Simone"},"url":"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/22542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/comments?post=22542"}],"version-history":[{"count":2,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/22542\/revisions"}],"predecessor-version":[{"id":22544,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/22542\/revisions\/22544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media\/22545"}],"wp:attachment":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media?parent=22542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/categories?post=22542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/tags?post=22542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}