{"id":23743,"date":"2009-06-04T16:56:00","date_gmt":"2009-06-04T19:56:00","guid":{"rendered":"https:\/\/staging.vetanco.com\/br\/?p=23743"},"modified":"2024-12-08T16:57:28","modified_gmt":"2024-12-08T19:57:28","slug":"vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque","status":"publish","type":"post","link":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/","title":{"rendered":"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque"},"content":{"rendered":"<p><em>Equipe t\u00e9cnica da Suinocultura participa de importante evento em N\u00e3o-Me-Toque \u2013 RS.<\/em><\/p>\n<p>A Vetanco do Brasil, atrav\u00e9s da equipe t\u00e9cnica de suinocultura, esteve presente na 10\u00ba Expodireto, que aconteceu de 16 a 20 de mar\u00e7o de 2009 em N\u00e3o-Me-Toque, RS.<\/p>\n<p>A empresa participou com estande, juntamente com Biobase e Ecobio, no pavilh\u00e3o da produ\u00e7\u00e3o.<\/p>\n<p>A Expodireto, idealizada e organizada pela Cotrijal, \u00e9 considerada uma das maiores feiras do Brasil, um palco de tecnologias, cultura e neg\u00f3cios.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[51,186],"class_list":["post-23743","post","type-post","status-publish","format-standard","hentry","category-eventos","tag-vetanco","tag-vetanco-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque - Vetanco Brasil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque - Vetanco Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-04T19:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-08T19:57:28+00:00\" \/>\n<meta name=\"author\" content=\"Simone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/\",\"name\":\"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque - Vetanco Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\"},\"datePublished\":\"2009-06-04T19:56:00+00:00\",\"dateModified\":\"2024-12-08T19:57:28+00:00\",\"author\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\"},\"breadcrumb\":{\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/staging.vetanco.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#website\",\"url\":\"https:\/\/staging.vetanco.com\/br\/\",\"name\":\"Vetanco Brasil\",\"description\":\"Produtos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de\",\"name\":\"Simone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"contentUrl\":\"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg\",\"caption\":\"Simone\"},\"url\":\"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque - Vetanco Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/","og_locale":"pt_BR","og_type":"article","og_title":"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque - Vetanco Brasil","og_url":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/","og_site_name":"Vetanco Brasil","article_published_time":"2009-06-04T19:56:00+00:00","article_modified_time":"2024-12-08T19:57:28+00:00","author":"Simone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Simone","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/","url":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/","name":"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque - Vetanco Brasil","isPartOf":{"@id":"https:\/\/staging.vetanco.com\/br\/#website"},"datePublished":"2009-06-04T19:56:00+00:00","dateModified":"2024-12-08T19:57:28+00:00","author":{"@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de"},"breadcrumb":{"@id":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.vetanco.com\/br\/vetanco-do-brasil-participa-da-expodireto-em-nao-me-toque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/staging.vetanco.com\/br\/"},{"@type":"ListItem","position":2,"name":"Vetanco do Brasil participa da Expodireto em N\u00e3o-Me-Toque"}]},{"@type":"WebSite","@id":"https:\/\/staging.vetanco.com\/br\/#website","url":"https:\/\/staging.vetanco.com\/br\/","name":"Vetanco Brasil","description":"Produtos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.vetanco.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de","name":"Simone","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/staging.vetanco.com\/br\/#\/schema\/person\/image\/","url":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","contentUrl":"https:\/\/staging.vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","caption":"Simone"},"url":"https:\/\/staging.vetanco.com\/br\/author\/sijantsch\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/23743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/comments?post=23743"}],"version-history":[{"count":2,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/23743\/revisions"}],"predecessor-version":[{"id":23745,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/posts\/23743\/revisions\/23745"}],"wp:attachment":[{"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/media?parent=23743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/categories?post=23743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.vetanco.com\/br\/wp-json\/wp\/v2\/tags?post=23743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}